{"id":14499,"date":"2024-01-03T11:45:59","date_gmt":"2024-01-03T16:45:59","guid":{"rendered":"https:\/\/canadianassstg.wpenginepowered.com\/?page_id=14499"},"modified":"2025-07-07T09:50:40","modified_gmt":"2025-07-07T13:50:40","slug":"politique-dappui","status":"publish","type":"page","link":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/","title":{"rendered":"Politiques"},"content":{"rendered":"\n<details class=\"wp-block-details has-medium-font-size is-layout-flow wp-block-details-is-layout-flow\"><summary>Politique d&rsquo;appui<\/summary>\n<p class=\"wp-block-paragraph\">L\u2019Association canadienne de recherche sur le VIH n\u2019avalise habituellement pas les prises de position politiques et d\u00e9clarations et messages ou initiatives de d\u00e9fense d\u2019autres organismes ou groupes, afin de respecter la diversit\u00e9 de points de vue de son vaste bassin de membres. Toutefois, \u00e0 titre de porte-parole national des chercheurs canadiens du domaine du VIH, l\u2019ACRV s\u2019engage \u00e0 utiliser sa plateforme pour faire conna\u00eetre les causes visant le bien de ses membres et des personnes vivant avec le VIH ou \u00e0 risque de le contracter.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details has-medium-font-size is-layout-flow wp-block-details-is-layout-flow\"><summary>Politique de r\u00e9vocation de prix de l\u2019ACRV<\/summary>\n<p class=\"wp-block-paragraph\"><strong>R\u00e9sum\u00e9&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Association canadienne de recherche sur le VIH (ACRV) accorde des d\u00e9corations et prix chaque ann\u00e9e pour souligner les contributions importantes \u00e0 la recherche sur le VIH au Canada. Ces prix sont choisis et \u00e9mis uniquement selon le jugement de l\u2019ACRV et \u00e0 sa discr\u00e9tion, et elle n\u2019est aucunement oblig\u00e9e de d\u00e9cerner ou de maintenir un prix accord\u00e9 ou d\u00e9cern\u00e9 \u00e0 une personne. L\u2019ACRV conserve le droit d\u2019octroyer, de suspendre ou de refuser d\u2019octroyer un prix \u00e0 quiconque. L\u2019ACRV conserve \u00e9galement le droit de r\u00e9voquer un prix apr\u00e8s octroi si, \u00e0 son seul jugement et \u00e0 sa seule discr\u00e9tion, elle constate que la r\u00e9vocation sert les meilleurs int\u00e9r\u00eats de l\u2019ACRV et de ses membres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Objet&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l\u2019attribution d\u2019un prix, l\u2019\u00e9thique professionnelle est d\u2019une importance cruciale. Lorsque l\u2019ACRV attribue un prix, cela veut dire qu\u2019elle juge que les contributions d\u2019une personne et son impulsion sur la recherche sur le VIH sont exemplaires. L\u2019ACRV tient compte de l\u2019effet, sur l\u2019entreprise, de la totalit\u00e9 du travail et de la conduite et de la r\u00e9putation \u00e9thique et professionnelle de la personne. L\u2019ACRV s\u2019attend que les titulaires de prix d\u00e9montrent que la participation \u00e0 la communaut\u00e9 de l\u2019ACRV et la reconnaissance de celle-ci sont des privil\u00e8ges et que les meneurs de la collectivit\u00e9 et autres personnes mises \u00e0 l\u2019honneur incarnent une conduite hautement professionnelle et d\u00e9ontologique dans leur travail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, tel que mentionn\u00e9 dans la documentation sur le programme des prix et bourses (\u00ab&nbsp;prix&nbsp;\u00bb) approuv\u00e9 de l\u2019ACRV, tous les laur\u00e9ats de prix doivent respecter les normes g\u00e9n\u00e9ralement reconnues d\u2019\u00e9thique professionnelle et d\u2019int\u00e9grit\u00e9 scientifique. Dans les rares cas o\u00f9 un laur\u00e9at de prix ne satisfait plus \u00e0 cette attente ou ne peut par ailleurs conserver et maintenir son statut de titulaire de prix, il faut suivre les lignes directrices et proc\u00e9dures \u00e9nonc\u00e9es ci-apr\u00e8s pour demander la r\u00e9vocation ou l\u2019\u00e9tude d\u2019une demande de r\u00e9vocation d\u2019un prix individuel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Port\u00e9e&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ACRV n\u2019accordera pas de prix \u00e0 une personne qui, \u00e0 la connaissance de l\u2019Association, a une conduite \u00e9thique sujette \u00e0 question, aussi longtemps que la question n\u2019a pas \u00e9t\u00e9 r\u00e9gl\u00e9e d\u00e9finitivement et de fa\u00e7on favorable \u00e0 la satisfaction et \u00e0 la discr\u00e9tion de l\u2019ACRV. La personne pressentie pour un prix (lorsqu\u2019elle l\u2019apprend), ou qui est titulaire du prix, reconna\u00eet qu\u2019elle doit en tout temps divulguer \u00e0 l\u2019ACRV l\u2019existence d\u2019un fait, d\u2019une situation ou d\u2019une circonstance qui pourrait avoir une incidence sur la d\u00e9cision de l\u2019Association d\u2019accorder un prix en vertu des dispositions de la pr\u00e9sente politique. En cas de non-divulgation, l\u2019ACRV peut retenir ou r\u00e9voquer un prix urse, \u00e0 sa seule discr\u00e9tion et conform\u00e9ment \u00e0 la politique et aux proc\u00e9dures \u00e9nonc\u00e9es aux pr\u00e9sentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, l\u2019ACRV, \u00e0 sa seule discr\u00e9tion, envisagera la r\u00e9vocation d\u2019un prix dans les cas d\u2019inconduite scientifique av\u00e9r\u00e9e, de manquement grave \u00e0 l\u2019\u00e9thique professionnelle ou si le titulaire du prix (de l\u2019avis de l\u2019ACRV) ne m\u00e9rite plus par ailleurs de conserver son statut de titulaire d\u2019un prix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l\u2019un ou l\u2019autre cas, dans l\u2019application de cette politique aux situations de questions cr\u00e9dibles mais non tranch\u00e9es, l\u2019ACRV retient son jugement et ne formule ni d\u00e9claration ni d\u00e9cision concernant une personne. La r\u00e9vocation, en pareil cas, peut plut\u00f4t \u00eatre consid\u00e9r\u00e9e comme une mesure pr\u00e9ventive pour prot\u00e9ger l\u2019int\u00e9grit\u00e9 des prix de l\u2019ACRV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toute demande de r\u00e9vocation de prix sera g\u00e9r\u00e9e conform\u00e9ment aux proc\u00e9dures \u00e9nonc\u00e9es ci-dessous. Les manquements \u00e0 l\u2019\u00e9thique professionnelle peuvent comprendre l\u2019inconduite sexuelle, la discrimination raciale ou autres infractions \u00e0 l\u2019\u00e9thique. Le harc\u00e8lement sexuel ou les repr\u00e9sailles en cas de refus, de d\u00e9claration de harc\u00e8lement ou d\u2019opposition \u00e0 cette d\u00e9claration ou autre inconduite sexuelle peut constituer un manquement grave \u00e0 l\u2019\u00e9thique professionnelle. La pr\u00e9sente politique couvre les activit\u00e9s professionnelles, quel que soit l\u2019endroit o\u00f9 elles se d\u00e9roulent. Cela comprend, sans s\u2019y limiter, les \u00e9tablissements universitaires, laboratoires, sites de recherche, stations de recherche, lieux de cours ext\u00e9rieurs, rencontres professionnelles ou tout autre cadre professionnel de ce type. La politique comprend les interactions avec des personnes, par exemple des coll\u00e8gues, subalternes, \u00e9tudiants, adjoints de recherche ou d\u2019enseignement ou autres personnes avec lesquelles le titulaire du prix interagit dans le cadre de ses activit\u00e9s professionnelles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La demande de r\u00e9vocation d\u2019un prix doit comprendre un rapport d\u2019enqu\u00eate \u00e9tayant les conclusions, les sanctions ou les mesures prises par un organisme ind\u00e9pendant ou une agence, une organisation affili\u00e9e \u00e0 l\u2019ACRV ou l\u2019ACRV elle-m\u00eame. Autre possibilit\u00e9, on peut faire annoncer publiquement l\u2019information dans le cadre d\u2019un rapport ou des mesures prises. Les comptes rendus publi\u00e9s dans les m\u00e9dias, \u00e0 eux seuls, pourraient ne pas suffire \u00e0 \u00e9tayer une demande de r\u00e9vocation. L\u2019ACRV n\u2019admettra que les demandes de r\u00e9vocation d\u00e9pos\u00e9es dans les deux (2)&nbsp;ans de la publication du rapport ou de l\u2019annonce concernant les conclusions, les sanctions ou les mesures, mais n\u2019\u00e9tudiera pas la demande si le titulaire du prix est d\u00e9c\u00e9d\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Proc\u00e9dures&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La demande de r\u00e9vocation d\u2019un prix (\u00ab&nbsp;demande&nbsp;\u00bb) doit \u00eatre pr\u00e9sent\u00e9e par \u00e9crit au secr\u00e9taire du Conseil d\u2019administration de l\u2019ACRV. Les demandes doivent \u00eatre exp\u00e9di\u00e9es par courriel \u00e0&nbsp;: <a href=\"mailto:%20info@cahr-acrv.ca\">info@cahr-acrv.ca<\/a>. Dans toutes les \u00e9tapes de ces proc\u00e9dures, en r\u00e8gle g\u00e9n\u00e9rale, l\u2019identit\u00e9 du demandeur ne sera pas divulgu\u00e9e par le bureau de l\u2019ACRV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La demande doit comprendre un rapport d\u2019enqu\u00eate et\/ou une annonce publique des conclusions ou des mesures prises (ou les liens aff\u00e9rents) provenant d\u2019une entit\u00e9 cr\u00e9dible, par exemple un organisme subventionnaire, une organisation professionnelle, un \u00e9tablissement universitaire, un tribunal ou encore, la reconnaissance de la conduite de la part du titulaire du prix. Seuls les membres de l\u2019ACRV peuvent pr\u00e9senter une demande. Il faut \u00e0 cet \u00e9gard pr\u00e9senter des renseignements d\u00e9taill\u00e9s sur les sources utilis\u00e9es afin de permettre la v\u00e9rification de l\u2019information. De plus, le membre doit accepter par \u00e9crit de maintenir l\u2019affaire confidentielle jusqu\u2019\u00e0 sa conclusion \u00e0 l\u2019ACRV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le personnel du bureau de l\u2019ACRV proc\u00e9dera \u00e0 un examen pr\u00e9liminaire pour savoir si la demande est importante, si la documentation est ad\u00e9quate et qu\u2019elle est conforme \u00e0 la pr\u00e9sente politique et \u00e0 ces proc\u00e9dures. \u00c0 la suite de cet examen, les proc\u00e9dures continueront de s\u2019appliquer ou la demande sera rejet\u00e9e sans pr\u00e9judice. Dans l\u2019un ou l\u2019autre cas, le personnel pr\u00e9parera un rapport \u00e0 l\u2019intention des administrateurs de l\u2019ACRV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au cours des proc\u00e9dures de r\u00e9vocation, les d\u00e9lib\u00e9rations sur les all\u00e9gations reposeront sur les donn\u00e9es probantes fournies. Dans le cadre des proc\u00e9dures de r\u00e9vocation, l\u2019ACRV ne m\u00e8nera pas d\u2019enqu\u00eate sur les plaintes ou les accusations au-del\u00e0 de l\u2019information pr\u00e9sent\u00e9e dans la demande et par ailleurs disponible publiquement (par exemple les documents ou les dossiers du tribunal).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En se fondant sur les documents pr\u00e9sent\u00e9s, le Conseil d\u2019administration d\u00e9cidera s\u2019il y a lieu d\u2019entamer des proc\u00e9dures de r\u00e9vocation ou de rejeter la demande. Le vote \u00e0 la majorit\u00e9 des administrateurs pr\u00e9sents suffit pour donner suite \u00e0 la demande. En pareil cas, le Conseil d\u2019administration cr\u00e9era un Comit\u00e9 sp\u00e9cial compos\u00e9 d\u2019au moins deux administrateurs actuels et d\u2019autres membres, nomm\u00e9s \u00e0 la discr\u00e9tion du Conseil d\u2019administration. Le Comit\u00e9 sp\u00e9cial exercera ses fonctions jusqu\u2019\u00e0 ce qu\u2019une d\u00e9cision soit prise \u00e0 propos de la demande, m\u00eame si le mandat de tel ou tel administrateur expire pendant cette p\u00e9riode.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si le Conseil d\u2019administration d\u00e9cide d\u2019aller de l\u2019avant, il \u00e9tablira un \u00e9ch\u00e9ancier du processus et le titulaire du prix sera inform\u00e9 par \u00e9crit de la demande, en toute confidentialit\u00e9. Le titulaire du prix recevra un avis de la demande, avec la documentation \u00e0 l\u2019appui. Il lui sera offert la possibilit\u00e9 de restituer son prix ou d\u2019en d\u00e9fendre le maintien. Il sera invit\u00e9 \u00e0 r\u00e9pondre par \u00e9crit \u00e0 la demande et, au besoin, \u00e0 faire un expos\u00e9 oral devant le Comit\u00e9 sp\u00e9cial, habituellement en mode virtuel. Le titulaire du prix participera sans autre repr\u00e9sentant \u00e0 cette conf\u00e9rence, qui sera de dur\u00e9e et de port\u00e9e limit\u00e9es conform\u00e9ment aux directives du Comit\u00e9 sp\u00e9cial. Le comit\u00e9 de s\u00e9lection des prix peut pr\u00e9parer une r\u00e9ponse \u00e9crite dans le d\u00e9lai d\u00e9fini par le Comit\u00e9 sp\u00e9cial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s expiration du d\u00e9lai de r\u00e9ponse, le Comit\u00e9 sp\u00e9cial \u00e9tudiera la demande initiale et toute r\u00e9ponse donn\u00e9e, y compris l\u2019expos\u00e9 de vive voix\/la conf\u00e9rence du titulaire du prix, le cas \u00e9ch\u00e9ant, et peut \u00e9galement tenir compte d\u2019autres renseignements pertinents des dossiers publics ou officiels. Le Comit\u00e9 sp\u00e9cial, apr\u00e8s d\u00e9lib\u00e9ration, votera sur une r\u00e9solution de r\u00e9vocation. Un vote positif de la majorit\u00e9 des membres du Comit\u00e9 sp\u00e9cial est n\u00e9cessaire pour que la r\u00e9solution soit adopt\u00e9e. La d\u00e9cision du Comit\u00e9 sp\u00e9cial est finale et sans appel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La d\u00e9cision prise, le Comit\u00e9 sp\u00e9cial pr\u00e9parera un rapport sommaire \u00e0 l\u2019intention du Conseil d\u2019administration. Il indiquera dans son rapport si la r\u00e9solution a \u00e9t\u00e9 adopt\u00e9e, mais non pas le d\u00e9tail du scrutin, non plus que les d\u00e9cisions des membres individuels du Comit\u00e9 sp\u00e9cial. Le personnel du bureau de l\u2019ACRV communiquera le rapport au membre qui a pr\u00e9sent\u00e9 la demande et aux anciens titulaires de prix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cas de r\u00e9vocation, le nom de l\u2019ancien titulaire de prix sera supprim\u00e9 de toutes les listes publiques des titulaires de prix. Si le personnel du bureau de l\u2019ACRV conclut \u00e0 la n\u00e9cessit\u00e9 d\u2019une annonce publique de la d\u00e9cision de r\u00e9vocation du prix, les facteurs contextuels ou les fondements de la r\u00e9vocation pourraient \u00eatre inclus dans l\u2019annonce, mais tout autre renseignement sur le demandeur et le Comit\u00e9 sp\u00e9cial et ses d\u00e9lib\u00e9rations demeurera confidentiel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Suppl\u00e9ment d\u2019information<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/ethics.gc.ca\/fra\/policy-politique_tcps2-eptc2_2022.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9nonc\u00e9 de politique des trois conseils&nbsp;: \u00c9thique de la recherche avec \u00eatres humains \u2013 EPTC&nbsp;2 (2022)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.canada.ca\/fr\/comite-coordination-recherche\/programmes\/directives-politiques\/politique-interorganismes-affirmation-citoyennete-appartenance-autochtones.html\" target=\"_blank\" rel=\"noreferrer noopener\">Politique interorganismes sur l\u2019affirmation de la citoyennet\u00e9 et de l\u2019appartenance autochtones (2024)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rcr.ethics.gc.ca\/fra\/framework-cadre-2021.html#a3\" target=\"_blank\" rel=\"noreferrer noopener\">Cadre de r\u00e9f\u00e9rence de trois organismes sur la conduite responsable de la recherche (2021) (Section 3.1.1 \u2013 Cas de violation de la Politique des trois organismes sur l\u2019int\u00e9grit\u00e9 de la recherche)<\/a><br>3.1.1 Cas de violation de la Politique des trois organismes sur l\u2019int\u00e9grit\u00e9 dans la recherche :<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Mauvaise gestion des conflits d\u2019int\u00e9r\u00eats&nbsp;: Le d\u00e9faut de reconna\u00eetre et de r\u00e9soudre ad\u00e9quatement tout conflit d\u2019int\u00e9r\u00eats r\u00e9el, potentiel ou apparent conform\u00e9ment \u00e0 la politique sur les conflits d\u2019int\u00e9r\u00eats en recherche de l\u2019\u00e9tablissement, emp\u00eachant ainsi l\u2019atteinte d\u2019un ou plusieurs des objectifs du Cadre de r\u00e9f\u00e9rence (article 1.3).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Fabrication&nbsp;: L\u2019invention de donn\u00e9es, de documents originaux, de m\u00e9thodes ou de r\u00e9sultats, y compris les graphiques et les images.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Falsification&nbsp;: La manipulation, la modification ou l\u2019omission de donn\u00e9es, de documents originaux, de m\u00e9thodes ou de r\u00e9sultats, y compris les graphiques et les images, sans mention appropri\u00e9e, de sorte que les travaux ne sont pas fid\u00e8lement repr\u00e9sent\u00e9s.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Destruction des donn\u00e9es ou des dossiers de recherche&nbsp;: La destruction de ses donn\u00e9es ou dossiers de recherche ou de ceux d\u2019une autre personne ou en violation de l\u2019entente de financement, des politiques de l\u2019\u00e9tablissement, des lois, des r\u00e8glements ou des normes professionnelles ou disciplinaires applicables. Cela comprend aussi la destruction de donn\u00e9es ou de dossiers pour \u00e9viter la d\u00e9couverte d\u2019un acte r\u00e9pr\u00e9hensible.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Plagiat&nbsp;: L\u2019utilisation des travaux publi\u00e9s ou non publi\u00e9s d\u2019une autre personne, notamment les th\u00e9ories, les concepts, les donn\u00e9es, les documents originaux, les m\u00e9thodes et les r\u00e9sultats, y compris les graphiques et les images, comme si c\u2019\u00e9tait les siens sans faire les mentions appropri\u00e9es et, le cas \u00e9ch\u00e9ant, sans permission.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Republication ou autoplagiat&nbsp;: La publication, en quelque langue que ce soit, de ses travaux, ou d\u2019une partie de ses travaux \u2013 y compris de ses donn\u00e9es qui ont d\u00e9j\u00e0 \u00e9t\u00e9 publi\u00e9s sans mention ad\u00e9quate de la source ou sans justification.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Attribution invalide du statut d\u2019auteur&nbsp;: L\u2019attribution inappropri\u00e9 du statut d\u2019auteur, notamment \u00e0 des personnes autres que celles ayant apport\u00e9 une contribution appr\u00e9ciable au contenu de la publication ou du document et en acceptant la responsabilit\u00e9.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Mention inad\u00e9quate&nbsp;: Le d\u00e9faut de reconna\u00eetre de mani\u00e8re appropri\u00e9e les contributeurs.<\/em><\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details has-medium-font-size is-layout-flow wp-block-details-is-layout-flow\"><summary>Code de d\u00e9ontologie du Congr\u00e8s<\/summary>\n<p class=\"wp-block-paragraph\">Le Congr\u00e8s annuel canadien de recherche sur le VIH\/sida (Congr\u00e8s de l\u2019ACRV) veut offrir \u00e0 tous les participants un environnement s\u00e9curitaire et sans harc\u00e8lement. Nous vous invitons \u00e0 nous aider \u00e0 faire de ce congr\u00e8s un lieu accueillant et respectueux pour tous les participants, sans \u00e9gard \u00e0 la race, au genre, \u00e0 l\u2019\u00e2ge, \u00e0 l\u2019orientation sexuelle, au handicap, \u00e0 l\u2019aspect physique, \u00e0 la taille corporelle, \u00e0 l\u2019origine nationale ou ethnique ou \u00e0 la religion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre de ce code de d\u00e9ontologie, nous nous attendons \u00e0 ce que tous les participants (personnes pr\u00e9sentes, conf\u00e9renciers, commanditaires, exposants, organisateurs et b\u00e9n\u00e9voles) aux Congr\u00e8s de l\u2019ACRV (ainsi qu\u2019aux ateliers, \u00e9v\u00e9nements sociaux ext\u00e9rieurs, activit\u00e9s en ligne et m\u00e9dias sociaux, avant, pendant et apr\u00e8s le congr\u00e8s proprement dit) traitent les autres avec respect.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aucun comportement irrespectueux ne sera tol\u00e9r\u00e9 aux \u00e9v\u00e9nements li\u00e9s \u00e0 l\u2019ACRV. De fa\u00e7on \u00e0 garantir un environnement favorable pour tous, nous avons d\u00e9fini ci-dessous quels sont les comportements inacceptables, le harc\u00e8lement, les cons\u00e9quences d\u2019un comportement inacceptable, et offrons des lignes directrices sur ce qu\u2019il faut faire si vous \u00eates t\u00e9moin ou vis\u00e9 par le harc\u00e8lement \u00e0 une activit\u00e9 de l\u2019ACRV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comportement inacceptable<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces comportements, quelle que soit leur forme, ne seront pas tol\u00e9r\u00e9s au congr\u00e8s&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Harc\u00e8lement (voir la d\u00e9finition compl\u00e8te ci-dessous)<\/li>\n\n\n\n<li>Intimidation, harc\u00e8lement criminel (stalking, suivre ou \u00e9pier une personne)<\/li>\n\n\n\n<li>Abus<\/li>\n\n\n\n<li>Discrimination<\/li>\n\n\n\n<li>Recours \u00e0 des propos, images ou v\u00eatements d\u00e9shumanisants. Cela comprend des expos\u00e9s, diapositives et le contenu des discours.<\/li>\n\n\n\n<li>Possession d\u2019un article pouvant servir d\u2019arme pouvant nuire aux autres<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Notre d\u00e9finition du harc\u00e8lement comprend ce qui suit&nbsp;:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comportement importun ou hostile, y compris les observations verbales ou \u00e9crites visant \u00e0 intimider, \u00e0 cr\u00e9er un malaise ou \u00e0 nuire \u00e0 la participation d\u2019une personne au congr\u00e8s<\/li>\n\n\n\n<li>Contact physique importun<\/li>\n\n\n\n<li>Attention sexuelle importune<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si vous \u00eates victime ou t\u00e9moin d\u2019un comportement inacceptable<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons besoin de votre aide pour veiller \u00e0 ce que l\u2019environnement du congr\u00e8s soit s\u00e9curitaire, responsable, libre de tout comportement inacceptable. Si vous \u00eates vis\u00e9 par n\u2019importe quelle forme de comportement inacceptable ou en \u00eates t\u00e9moin, veuillez porter vos pr\u00e9occupations \u00e0 l\u2019attention imm\u00e9diate du personnel du congr\u00e8s (qui portera des tee-shirts du congr\u00e8s facilement identifiables) ou \u00e9crivez-nous par courriel \u00e0 <a href=\"mailto:info@cahr-acrv.ca\" target=\"_blank\" rel=\"noreferrer noopener\">info@cahr-acrv.ca.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le personnel du congr\u00e8s sera tout dispos\u00e9 \u00e0 aider les personnes qui sont victimes de harc\u00e8lement \u00e0 se sentir en s\u00e9curit\u00e9 pour la dur\u00e9e du congr\u00e8s. Nous adressons d\u2019avance nos remerciements aux participants du congr\u00e8s pour leur aide afin que l\u2019\u00e9v\u00e9nement soit s\u00e9curitaire, accueillant et respectueux pour tous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cons\u00e9quences d\u2019un comportement inacceptable<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les participants invit\u00e9s \u00e0 mettre fin \u00e0 un comportement inacceptable doivent obtemp\u00e9rer imm\u00e9diatement. Le participant qui viole le code de d\u00e9ontologie peut \u00eatre expuls\u00e9 du congr\u00e8s et des activit\u00e9s connexes sans remboursement et\/ou \u00eatre interdit aux \u00e9v\u00e9nements futurs \u00e0 la discr\u00e9tion des organisateurs de l\u2019ACRV ou du Conseil d\u2019administration de l\u2019Association.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cahr-acrv.ca\/wp-content\/uploads\/2019\/11\/Code-of-Conduct-CAHR-Conference-November-11-2019-FINAL-fr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9l\u00e9charger la version imprimable<\/a><\/p>\n<\/details>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-14499","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politiques &#8211; ACRV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politiques &#8211; ACRV\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/\" \/>\n<meta property=\"og:site_name\" content=\"ACRV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CanadianAssociationforHIVResearch\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T13:50:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CAHR_ACRV\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/fr\\\/politique-dappui\\\/\",\"url\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/fr\\\/politique-dappui\\\/\",\"name\":\"Politiques &#8211; ACRV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/#website\"},\"datePublished\":\"2024-01-03T16:45:59+00:00\",\"dateModified\":\"2025-07-07T13:50:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/fr\\\/politique-dappui\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cahr-acrv.ca\\\/fr\\\/politique-dappui\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/fr\\\/politique-dappui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/\",\"name\":\"ACRV\",\"description\":\"L'association canadienne de recherche sur le VIH\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/#organization\",\"name\":\"Canadian Association for HIV Research\",\"alternateName\":\"CAHR\",\"url\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cahr-organization-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cahr-organization-logo.png\",\"width\":696,\"height\":696,\"caption\":\"Canadian Association for HIV Research\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cahr-acrv.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CanadianAssociationforHIVResearch\",\"https:\\\/\\\/x.com\\\/CAHR_ACRV\",\"https:\\\/\\\/bsky.app\\\/profile\\\/cahr-acrv.bsky.social\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CAHRACRV\",\"https:\\\/\\\/www.instagram.com\\\/cahr_acrv\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/canadian-association-for-hiv-research\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politiques &#8211; ACRV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/","og_locale":"fr_FR","og_type":"article","og_title":"Politiques &#8211; ACRV","og_url":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/","og_site_name":"ACRV","article_publisher":"https:\/\/www.facebook.com\/CanadianAssociationforHIVResearch","article_modified_time":"2025-07-07T13:50:40+00:00","twitter_card":"summary_large_image","twitter_site":"@CAHR_ACRV","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/","url":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/","name":"Politiques &#8211; ACRV","isPartOf":{"@id":"https:\/\/www.cahr-acrv.ca\/#website"},"datePublished":"2024-01-03T16:45:59+00:00","dateModified":"2025-07-07T13:50:40+00:00","breadcrumb":{"@id":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cahr-acrv.ca\/fr\/politique-dappui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cahr-acrv.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Politiques"}]},{"@type":"WebSite","@id":"https:\/\/www.cahr-acrv.ca\/#website","url":"https:\/\/www.cahr-acrv.ca\/","name":"ACRV","description":"L'association canadienne de recherche sur le VIH","publisher":{"@id":"https:\/\/www.cahr-acrv.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cahr-acrv.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cahr-acrv.ca\/#organization","name":"Canadian Association for HIV Research","alternateName":"CAHR","url":"https:\/\/www.cahr-acrv.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cahr-acrv.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.cahr-acrv.ca\/wp-content\/uploads\/2025\/06\/cahr-organization-logo.png","contentUrl":"https:\/\/www.cahr-acrv.ca\/wp-content\/uploads\/2025\/06\/cahr-organization-logo.png","width":696,"height":696,"caption":"Canadian Association for HIV Research"},"image":{"@id":"https:\/\/www.cahr-acrv.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CanadianAssociationforHIVResearch","https:\/\/x.com\/CAHR_ACRV","https:\/\/bsky.app\/profile\/cahr-acrv.bsky.social","https:\/\/www.youtube.com\/user\/CAHRACRV","https:\/\/www.instagram.com\/cahr_acrv\/","https:\/\/www.linkedin.com\/company\/canadian-association-for-hiv-research\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/pages\/14499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/comments?post=14499"}],"version-history":[{"count":0,"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/pages\/14499\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cahr-acrv.ca\/fr\/wp-json\/wp\/v2\/media?parent=14499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}